{"id":82,"count":1,"description":"","link":"https:\/\/www.kiwidrug.com\/blog\/tag\/semaglutide\/","name":"Semaglutide","slug":"semaglutide","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v14.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Semaglutide Archives - Kiwi Health<\/title>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<meta name=\"googlebot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta name=\"bingbot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kiwidrug.com\/blog\/tag\/semaglutide\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Semaglutide Archives - Kiwi Health\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kiwidrug.com\/blog\/tag\/semaglutide\/\" \/>\n<meta property=\"og:site_name\" content=\"Kiwi Health\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.kiwidrug.com\/blog\/#website\",\"url\":\"https:\/\/www.kiwidrug.com\/blog\/\",\"name\":\"Kiwi Health\",\"description\":\"Health and wellness blog by Kiwi\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.kiwidrug.com\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.kiwidrug.com\/blog\/tag\/semaglutide\/#webpage\",\"url\":\"https:\/\/www.kiwidrug.com\/blog\/tag\/semaglutide\/\",\"name\":\"Semaglutide Archives - Kiwi Health\",\"isPartOf\":{\"@id\":\"https:\/\/www.kiwidrug.com\/blog\/#website\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.kiwidrug.com\/blog\/tag\/semaglutide\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.kiwidrug.com\/blog\/wp-json\/wp\/v2\/tags\/82"}],"collection":[{"href":"https:\/\/www.kiwidrug.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.kiwidrug.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.kiwidrug.com\/blog\/wp-json\/wp\/v2\/posts?tags=82"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}